{"id":117422,"date":"2025-06-18T18:24:27","date_gmt":"2025-06-18T16:24:27","guid":{"rendered":"https:\/\/yasminfood.ch\/product\/gekochte-400g-sonnen\/"},"modified":"2025-06-20T00:47:35","modified_gmt":"2025-06-19T22:47:35","slug":"gekochte-400g-sonnen","status":"publish","type":"product","link":"https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/","title":{"rendered":"Gekochte 400g Sonnen"},"content":{"rendered":"<p><strong>Gekochte 400g Sonnen<\/strong><\/p>\n<ul>\n<li data-start=\"147\" data-end=\"286\">Ein k\u00f6stliches und einfach zuzubereitendes traditionelles Dessert mit Zimt- und Anisgeschmack<\/li>\n<li data-start=\"147\" data-end=\"286\">Ideal f\u00fcr die Zeit nach der Geburt oder als gesundes warmes Getr\u00e4nk.<\/li>\n<li data-start=\"147\" data-end=\"286\">\n<p data-start=\"339\" data-end=\"564\">Gekochtes ist eines der beliebtesten libanesischen und syrischen Lebensmittel, das bei Geburten serviert wird, und es ist reich an n\u00fctzlichen Elementen f\u00fcr den K\u00f6rper. <\/p>\n<p data-start=\"566\" data-end=\"729\">Die Packung wird mit <strong data-start=\"581\" data-end=\"615\">4 Instant-Beuteln (je 100 g) geliefert,<\/strong> und jeder Beutel reicht aus, um 4 Tassen zuzubereiten. Die Zubereitungsmethode ist schnell und einfach und eignet sich daher ideal f\u00fcr die Gastfreundschaft oder den pers\u00f6nlichen Gebrauch.<\/p>\n<p data-start=\"731\" data-end=\"745\"><strong data-start=\"731\" data-end=\"745\">\u2705 Funktionen:<\/strong><\/p>\n<ul data-start=\"746\" data-end=\"874\">\n<li data-start=\"746\" data-end=\"784\">\n<p data-start=\"748\" data-end=\"784\">Nat\u00fcrlicher Geschmack, reich an Zimt und Anis<\/p>\n<\/li>\n<li data-start=\"785\" data-end=\"812\">\n<p data-start=\"787\" data-end=\"812\">4 einfach zu bedienende Umschl\u00e4ge<\/p>\n<\/li>\n<li data-start=\"813\" data-end=\"847\">\n<p data-start=\"815\" data-end=\"847\">Geeignet f\u00fcr das Wochenbett und n\u00fctzlich f\u00fcr die Verdauung<\/p>\n<\/li>\n<li data-start=\"848\" data-end=\"874\">\n<p data-start=\"850\" data-end=\"874\">Ohne Konservierungsstoffe<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"876\" data-end=\"968\"><strong data-start=\"876\" data-end=\"896\">\ud83d\udce6 Nettogewicht:<\/strong> 400 g (4 \u00d7 100 g)<br data-start=\"914\" data-end=\"917\"><strong data-start=\"917\" data-end=\"932\">Herkunftsland:<\/strong> Libanon<br data-start=\"938\" data-end=\"941\"><strong data-start=\"941\" data-end=\"962\">Hersteller:<\/strong> Shamsin<\/p>\n<p data-start=\"970\" data-end=\"1117\"><strong data-start=\"970\" data-end=\"991\">\ud83d\udd38 Kochen:<\/strong><br data-start=\"991\" data-end=\"994\">Den Inhalt des Umschlags mit Wasser verr\u00fchren und unter R\u00fchren zum Kochen bringen, bis die richtige Konsistenz erreicht ist, und mit Kokosnuss und N\u00fcssen nach Geschmack garniert servieren. <\/p>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p class=\"ai-optimize-26 ai-optimize-introduction\"><strong>Gekochte 400g Sonnen<\/strong><\/p>\n<ul>\n<li class=\"ai-optimize-27\" data-start=\"147\" data-end=\"286\">Ein k\u00f6stliches und einfach zuzubereitendes traditionelles Dessert mit Zimt- und Anisgeschmack<\/li>\n<li class=\"ai-optimize-27\" data-start=\"147\" data-end=\"286\">Ideal f\u00fcr die Zeit nach der Geburt oder als gesundes warmes Getr\u00e4nk.<\/li>\n<li class=\"ai-optimize-27\" data-start=\"147\" data-end=\"286\">Gekochtes ist eines der beliebtesten libanesischen und syrischen Lebensmittel und ist reich an n\u00fctzlichen Elementen f\u00fcr den K\u00f6rper.<\/li>\n<\/ul>\n","protected":false},"featured_media":117407,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[2332],"product_cat":[301,297],"product_tag":[],"class_list":["post-117422","product","type-product","status-publish","has-post-thumbnail","product_brand-chamsine-de","product_cat-arabische-suessigkeiten","product_cat-dessert-chips-2","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gekochte 400g Sonnen - Yasmin Food<\/title>\n<meta name=\"description\" content=\"Genie\u00dfen Sie die S\u00fc\u00dfe eines Suds aus 400 g Shamsine, einem traditionellen Getr\u00e4nk mit Zimt und Anis. Perfekt f\u00fcr die Zeit nach der Geburt, bestellen Sie es jetzt! \u2705 Yasmin Food\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gekochte 400g Sonnen\" \/>\n<meta property=\"og:description\" content=\"Gekochte 400g Sonnen   Ein k\u00f6stliches und einfach zuzubereitendes traditionelles Dessert mit Zimt- und Anisgeschmack  Ideal f\u00fcr die Zeit nach der Geburt oder als gesundes warmes Getr\u00e4nk.  Gekochtes ist eines der beliebtesten libanesischen und syrischen Lebensmittel und ist reich an n\u00fctzlichen Elementen f\u00fcr den K\u00f6rper.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/\" \/>\n<meta property=\"og:site_name\" content=\"Yasmin Food\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/yasminmarkt1\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T22:47:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/yasminfood.ch\/wp-content\/uploads\/2025\/06\/\u0645\u063a\u0644\u064a-400\u063a-\u0634\u0645\u0633\u064a\u0646.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1890\" \/>\n\t<meta property=\"og:image:height\" content=\"1890\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"3.50&nbsp;&#067;&#072;&#070;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/product\\\/gekochte-400g-sonnen\\\/\",\"url\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/product\\\/gekochte-400g-sonnen\\\/\",\"name\":\"Gekochte 400g Sonnen - Yasmin Food\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/product\\\/gekochte-400g-sonnen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/product\\\/gekochte-400g-sonnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yasminfood.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/\u0645\u063a\u0644\u064a-400\u063a-\u0634\u0645\u0633\u064a\u0646.png\",\"datePublished\":\"2025-06-18T16:24:27+00:00\",\"dateModified\":\"2025-06-19T22:47:35+00:00\",\"description\":\"Genie\u00dfen Sie die S\u00fc\u00dfe eines Suds aus 400 g Shamsine, einem traditionellen Getr\u00e4nk mit Zimt und Anis. Perfekt f\u00fcr die Zeit nach der Geburt, bestellen Sie es jetzt! \u2705 Yasmin Food\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/product\\\/gekochte-400g-sonnen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yasminfood.ch\\\/de\\\/product\\\/gekochte-400g-sonnen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/product\\\/gekochte-400g-sonnen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/yasminfood.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/\u0645\u063a\u0644\u064a-400\u063a-\u0634\u0645\u0633\u064a\u0646.png\",\"contentUrl\":\"https:\\\/\\\/yasminfood.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/\u0645\u063a\u0644\u064a-400\u063a-\u0634\u0645\u0633\u064a\u0646.png\",\"width\":1890,\"height\":1890,\"caption\":\"Gekochte 400g Sonnen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/product\\\/gekochte-400g-sonnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/zuhause\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dessert &amp; Chips\",\"item\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/produkt-kategorie\\\/dessert-chips-2\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Gekochte 400g Sonnen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/\",\"name\":\"\u064a\u0627\u0633\u0645\u064a\u0646 \u0645\u0627\u0631\u0643\u062a\",\"description\":\"Alles, was Sie brauchen, an einem Ort\",\"publisher\":{\"@id\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/#organization\"},\"alternateName\":\"Yasmin Food\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/#organization\",\"name\":\"\u064a\u0627\u0633\u0645\u064a\u0646 \u0645\u0627\u0631\u0643\u062a\",\"alternateName\":\"Yasmin Food\",\"url\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/yasminfood.ch\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/yasmin-food-header-logo.png\",\"contentUrl\":\"https:\\\/\\\/yasminfood.ch\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/yasmin-food-header-logo.png\",\"width\":330,\"height\":120,\"caption\":\"\u064a\u0627\u0633\u0645\u064a\u0646 \u0645\u0627\u0631\u0643\u062a\"},\"image\":{\"@id\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/yasminmarkt1\",\"https:\\\/\\\/www.tiktok.com\\\/@yasminmarkt\",\"https:\\\/\\\/www.instagram.com\\\/yasmin.markt1\\\/\",\"https:\\\/\\\/api.whatsapp.com\\\/send\\\/?phone=41799000104\"],\"publishingPrinciples\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/shop\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/yasminfood.ch\\\/de\\\/shop\\\/\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"3.50\" \/>\n<meta property=\"product:price:currency\" content=\"CHF\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gekochte 400g Sonnen - Yasmin Food","description":"Genie\u00dfen Sie die S\u00fc\u00dfe eines Suds aus 400 g Shamsine, einem traditionellen Getr\u00e4nk mit Zimt und Anis. Perfekt f\u00fcr die Zeit nach der Geburt, bestellen Sie es jetzt! \u2705 Yasmin Food","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/","og_locale":"de_DE","og_type":"article","og_title":"Gekochte 400g Sonnen","og_description":"Gekochte 400g Sonnen   Ein k\u00f6stliches und einfach zuzubereitendes traditionelles Dessert mit Zimt- und Anisgeschmack  Ideal f\u00fcr die Zeit nach der Geburt oder als gesundes warmes Getr\u00e4nk.  Gekochtes ist eines der beliebtesten libanesischen und syrischen Lebensmittel und ist reich an n\u00fctzlichen Elementen f\u00fcr den K\u00f6rper.","og_url":"https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/","og_site_name":"Yasmin Food","article_publisher":"https:\/\/www.facebook.com\/yasminmarkt1","article_modified_time":"2025-06-19T22:47:35+00:00","og_image":[{"width":1890,"height":1890,"url":"https:\/\/yasminfood.ch\/wp-content\/uploads\/2025\/06\/\u0645\u063a\u0644\u064a-400\u063a-\u0634\u0645\u0633\u064a\u0646.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Preis":"3.50&nbsp;&#67;&#72;&#70;","Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/","url":"https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/","name":"Gekochte 400g Sonnen - Yasmin Food","isPartOf":{"@id":"https:\/\/yasminfood.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/#primaryimage"},"image":{"@id":"https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/#primaryimage"},"thumbnailUrl":"https:\/\/yasminfood.ch\/wp-content\/uploads\/2025\/06\/\u0645\u063a\u0644\u064a-400\u063a-\u0634\u0645\u0633\u064a\u0646.png","datePublished":"2025-06-18T16:24:27+00:00","dateModified":"2025-06-19T22:47:35+00:00","description":"Genie\u00dfen Sie die S\u00fc\u00dfe eines Suds aus 400 g Shamsine, einem traditionellen Getr\u00e4nk mit Zimt und Anis. Perfekt f\u00fcr die Zeit nach der Geburt, bestellen Sie es jetzt! \u2705 Yasmin Food","breadcrumb":{"@id":"https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/#primaryimage","url":"https:\/\/yasminfood.ch\/wp-content\/uploads\/2025\/06\/\u0645\u063a\u0644\u064a-400\u063a-\u0634\u0645\u0633\u064a\u0646.png","contentUrl":"https:\/\/yasminfood.ch\/wp-content\/uploads\/2025\/06\/\u0645\u063a\u0644\u064a-400\u063a-\u0634\u0645\u0633\u064a\u0646.png","width":1890,"height":1890,"caption":"Gekochte 400g Sonnen"},{"@type":"BreadcrumbList","@id":"https:\/\/yasminfood.ch\/de\/product\/gekochte-400g-sonnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/yasminfood.ch\/de\/zuhause\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/yasminfood.ch\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Dessert &amp; Chips","item":"https:\/\/yasminfood.ch\/de\/produkt-kategorie\/dessert-chips-2\/"},{"@type":"ListItem","position":4,"name":"Gekochte 400g Sonnen"}]},{"@type":"WebSite","@id":"https:\/\/yasminfood.ch\/de\/#website","url":"https:\/\/yasminfood.ch\/de\/","name":"\u064a\u0627\u0633\u0645\u064a\u0646 \u0645\u0627\u0631\u0643\u062a","description":"Alles, was Sie brauchen, an einem Ort","publisher":{"@id":"https:\/\/yasminfood.ch\/de\/#organization"},"alternateName":"Yasmin Food","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yasminfood.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/yasminfood.ch\/de\/#organization","name":"\u064a\u0627\u0633\u0645\u064a\u0646 \u0645\u0627\u0631\u0643\u062a","alternateName":"Yasmin Food","url":"https:\/\/yasminfood.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/yasminfood.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/yasminfood.ch\/wp-content\/uploads\/2025\/05\/yasmin-food-header-logo.png","contentUrl":"https:\/\/yasminfood.ch\/wp-content\/uploads\/2025\/05\/yasmin-food-header-logo.png","width":330,"height":120,"caption":"\u064a\u0627\u0633\u0645\u064a\u0646 \u0645\u0627\u0631\u0643\u062a"},"image":{"@id":"https:\/\/yasminfood.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/yasminmarkt1","https:\/\/www.tiktok.com\/@yasminmarkt","https:\/\/www.instagram.com\/yasmin.markt1\/","https:\/\/api.whatsapp.com\/send\/?phone=41799000104"],"publishingPrinciples":"https:\/\/yasminfood.ch\/de\/shop\/","ownershipFundingInfo":"https:\/\/yasminfood.ch\/de\/shop\/"}]},"product_price_amount":"3.50","product_price_currency":"CHF","og_availability":"instock","product_availability":"instock","product_condition":"new"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/yasminfood.ch\/de\/wp-json\/wp\/v2\/product\/117422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yasminfood.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/yasminfood.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/yasminfood.ch\/de\/wp-json\/wp\/v2\/comments?post=117422"}],"version-history":[{"count":0,"href":"https:\/\/yasminfood.ch\/de\/wp-json\/wp\/v2\/product\/117422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yasminfood.ch\/de\/wp-json\/wp\/v2\/media\/117407"}],"wp:attachment":[{"href":"https:\/\/yasminfood.ch\/de\/wp-json\/wp\/v2\/media?parent=117422"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/yasminfood.ch\/de\/wp-json\/wp\/v2\/product_brand?post=117422"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/yasminfood.ch\/de\/wp-json\/wp\/v2\/product_cat?post=117422"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/yasminfood.ch\/de\/wp-json\/wp\/v2\/product_tag?post=117422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}